{"id":13355,"date":"2024-03-25T17:29:25","date_gmt":"2024-03-25T17:29:25","guid":{"rendered":"https:\/\/staging.weshyft.com\/?p=13355"},"modified":"2024-03-25T17:35:03","modified_gmt":"2024-03-25T17:35:03","slug":"cbam-das-co2-grenzausgleichssystem-der-eu","status":"publish","type":"post","link":"https:\/\/www.weshyft.com\/en\/cbam-das-co2-grenzausgleichssystem-der-eu\/","title":{"rendered":"CBAM \u2013 das CO2 Grenzausgleichssystem der EU"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"13355\" class=\"elementor elementor-13355\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47ac58d3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"47ac58d3\" data-element_type=\"section\" id=\"postcontent\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-17e93964\" data-id=\"17e93964\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46f35047 elementor-widget elementor-widget-text-editor\" data-id=\"46f35047\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><em>Der CBAM (Carbon Border Adjustment Mechanism) ist am 01. Oktober 2023 in Kraft getreten und wurde damit zur Pflicht f\u00fcr viele Importeure in der EU. Dieser Artikel gibt einen \u00dcberblick \u00fcber die Hintergr\u00fcnde und Inhalte sowie zu Zeitplan und Anforderungen f\u00fcr betroffene Unternehmen des CBAM. Die erste Frist ist bereits am 31. Januar 2024, zu der CBAM-Berichte bei der EU-Kommission eingereicht werden m\u00fcssen.<\/em><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71dea720 elementor-invisible elementor-widget elementor-widget-post-info\" data-id=\"71dea720\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-9ab8179 elementor-inline-item\" itemprop=\"datePublished\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-date\">\n\t\t\t\t\t\t\t\t\t\t<time>March 25, 2024<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-98f547c elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-clock\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256,8C119,8,8,119,8,256S119,504,256,504,504,393,504,256,393,8,256,8Zm92.49,313h0l-20,25a16,16,0,0,1-22.49,2.5h0l-67-49.72a40,40,0,0,1-15-31.23V112a16,16,0,0,1,16-16h32a16,16,0,0,1,16,16V256l58,42.5A16,16,0,0,1,348.49,321Z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-custom\">\n\t\t\t\t\t\t\t\t\t\tLesezeit: 7 Minuten\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59544a2a elementor-widget elementor-widget-heading\" data-id=\"59544a2a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Was ist der CBAM? <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a9d51be elementor-widget elementor-widget-text-editor\" data-id=\"7a9d51be\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Das CO2-Grenzausgleichssystem CBAM ist ein Instrument der EU-Klimapolitik. Die Verordnung EU 2023\/956 wurde im Kontext des Fit-for-55-Pakets, also der Reduktion der CO2-Emissionen um 55 Prozent im Vergleich zu 1990 bis 2030, eingef\u00fchrt. Im Rahmen dieses Pakets wurde 2021 auch das Europ\u00e4ische Emissionshandelssystem (EU-ETS), welches aus der Umsetzung des Kyoto-Protokolls 2005 heraus entstand, angepasst.\u00a0<\/p><p>Zentral f\u00fcr das EU-ETS ist das Cap and Trade-System, welches Unternehmen Emissionsgrenzen setzt und ihnen erm\u00f6glicht, Emissionsrechte in Form von Zertifikaten zuzukaufen und zu handeln. Durch die schrittweise Reduktion der zugeteilten kostenlosen EU-ETS-Zertifikate sollen die Klimaziele erreicht werden. Daraus hat sich das Problem des \u201eCarbon Leakage\u201c ergeben.<\/p><p>Der CBAM steht nun im Fokus der Bem\u00fchungen, das \u201eCarbon Leakage\u201c zu bek\u00e4mpfen. Dieser Begriff beschreibt die Verlagerung von CO2-intensiven Produktionen in L\u00e4nder mit niedrigeren CO2-Preisen, um der CO2-Bepreisung der EU zu entgehen. Importeure von CBAM-Waren werden nun verpflichtet, CBAM-Zertifikate zu erwerben. Dies soll sicherzustellen, dass heimische Unternehmen, die vergleichbare Waren herstellen, nicht durch die CO2-Bepreisung benachteiligt werden. Der Preis der CBAM-Zertifikate entspricht dem Preis f\u00fcr EU-ETS. Auch die Verpflichtung zum Erwerb von CBAM-Zertifikaten wird gekoppelt an das Ma\u00df, in dem die kostenlose EU-ETS-Zuteilung verringert wird. Bis 2034 sollen keine kostenlosen Zertifikate mehr vergeben werden und somit die CBAM-Zertifikate verpflichtend f\u00fcr 100 % der grauen Emissionen eingef\u00fchrter Waren.<\/p><p>Der CBAM verfolgt die folgenden \u00fcbergeordneten Ziele:<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54d4016 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"54d4016\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-thumbtack\" viewbox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M298.028 214.267L285.793 96H328c13.255 0 24-10.745 24-24V24c0-13.255-10.745-24-24-24H56C42.745 0 32 10.745 32 24v48c0 13.255 10.745 24 24 24h42.207L85.972 214.267C37.465 236.82 0 277.261 0 328c0 13.255 10.745 24 24 24h136v104.007c0 1.242.289 2.467.845 3.578l24 48c2.941 5.882 11.364 5.893 14.311 0l24-48a8.008 8.008 0 0 0 .845-3.578V352h136c13.255 0 24-10.745 24-24-.001-51.183-37.983-91.42-85.973-113.733z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">die Effektivit\u00e4t des EU-ETS st\u00e4rken durch die Verhinderung des \u201eCarbon Leakage\u201c1<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-thumbtack\" viewbox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M298.028 214.267L285.793 96H328c13.255 0 24-10.745 24-24V24c0-13.255-10.745-24-24-24H56C42.745 0 32 10.745 32 24v48c0 13.255 10.745 24 24 24h42.207L85.972 214.267C37.465 236.82 0 277.261 0 328c0 13.255 10.745 24 24 24h136v104.007c0 1.242.289 2.467.845 3.578l24 48c2.941 5.882 11.364 5.893 14.311 0l24-48a8.008 8.008 0 0 0 .845-3.578V352h136c13.255 0 24-10.745 24-24-.001-51.183-37.983-91.42-85.973-113.733z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">globale CO2-Emissionen reduzieren und Impulse f\u00fcr eine klimafreundlichere Produktion in Drittl\u00e4ndern setzen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-thumbtack\" viewbox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M298.028 214.267L285.793 96H328c13.255 0 24-10.745 24-24V24c0-13.255-10.745-24-24-24H56C42.745 0 32 10.745 32 24v48c0 13.255 10.745 24 24 24h42.207L85.972 214.267C37.465 236.82 0 277.261 0 328c0 13.255 10.745 24 24 24h136v104.007c0 1.242.289 2.467.845 3.578l24 48c2.941 5.882 11.364 5.893 14.311 0l24-48a8.008 8.008 0 0 0 .845-3.578V352h136c13.255 0 24-10.745 24-24-.001-51.183-37.983-91.42-85.973-113.733z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">sicherstellen, dass der CO2-Preis von importierten Waren dem europ\u00e4ischen CO2-Preis entspricht und somit keine Wettbewerbsnachteile entstehen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99200c2 elementor-widget elementor-widget-heading\" data-id=\"99200c2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Welche Unternehmen sind von dem CBAM betroffen?<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fa6eac elementor-widget elementor-widget-text-editor\" data-id=\"1fa6eac\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Im Gegensatz zur CSRD oder CSDDD ist der CBAM nicht an die Unternehmensgr\u00f6\u00dfe wie bspw. Mitarbeitendenzahl oder Bilanzsumme gekn\u00fcpft, sondern gilt f\u00fcr den Import von CO2-intensiven Warengruppen. Verantwortlich ist der Importeur (ab 150 Euro Warenwert). Im Anhang I. der Verordnung sind die genauen Waren aufgelistet. Relevant sind hierbei die Codes der Kombinierten Nomenklatur (KN).<\/p><p>Die Warengruppen sind bis 2026 vorbehaltlich und k\u00f6nnen noch durch die EU angepasst werden. Bspw. soll gepr\u00fcft werden, ob Chemikalien und Polymere in den CBAM eingeschlossen werden. Letztendlich sollen bis 2030 die Produkte des CBAM an die des EU-ETS angepasst sein.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bb4be4 elementor-widget elementor-widget-image\" data-id=\"1bb4be4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1536\" height=\"245\" src=\"https:\/\/www.weshyft.com\/wp-content\/uploads\/2024\/03\/Products-1536x245.png\" class=\"attachment-1536x1536 size-1536x1536 wp-image-13383\" alt=\"CBAM Products\" srcset=\"https:\/\/www.weshyft.com\/wp-content\/uploads\/2024\/03\/Products-1536x245.png 1536w, https:\/\/www.weshyft.com\/wp-content\/uploads\/2024\/03\/Products-300x48.png 300w, https:\/\/www.weshyft.com\/wp-content\/uploads\/2024\/03\/Products-1024x163.png 1024w, https:\/\/www.weshyft.com\/wp-content\/uploads\/2024\/03\/Products-768x122.png 768w, https:\/\/www.weshyft.com\/wp-content\/uploads\/2024\/03\/Products-2048x326.png 2048w, https:\/\/www.weshyft.com\/wp-content\/uploads\/2024\/03\/Products-18x3.png 18w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6d97d2 elementor-widget elementor-widget-heading\" data-id=\"b6d97d2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Timeline und Anforderungen des CBAM <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d3bc1b6 elementor-widget elementor-widget-text-editor\" data-id=\"1d3bc1b6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Die Verpflichtungen des CBAM werden in einer \u00dcbergangsphase schrittweise ausgeweitet, um Unternehmen Vorbereitungszeit einzur\u00e4umen.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3736135 elementor-widget elementor-widget-jet-timeline\" data-id=\"3736135\" data-element_type=\"widget\" data-widget_type=\"jet-timeline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-jet-timeline jet-elements\"><div class=\"jet-timeline jet-timeline--align-center jet-timeline--align-middle\">\n\t<div class=\"jet-timeline__line\"><div class=\"jet-timeline__line-progress\"><\/div><\/div>\n\t<div class=\"jet-timeline-list\"><div class=\"jet-timeline-item  elementor-repeater-item-7303c5c jet-timeline-item--image-inside\">\n\t<div class=\"timeline-item__card\">\n\t\t<div class=\"timeline-item__card-inner\">\n\t\t\t\t\t\t\t\t<div class=\"timeline-item__card-content\">\n\t\t\t\t\t<div class=\"timeline-item__meta\"><div class=\"timeline-item__meta-content\">1. Oktober 2023<\/div><\/div><h5 class=\"timeline-item__card-title\">CBAM tritt in Kraft und Beginn der \u00dcbergangsphase<\/h5><div class=\"timeline-item__card-desc\">Erf\u00fcllung erster Berichts- und Meldepflichten (beschr\u00e4nkte Verpflichtungen): Berechnung der direkten und indirekten CO2-Emissionen der importierten Waren & Registrierung im CBAM-Meldeportal <\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"timeline-item__card-arrow\"><\/div>\n\t<\/div>\n\t<div class=\"timeline-item__point\"><div class=\"timeline-item__point-content timeline-item__point-content--icon\"><span class=\"jet-elements-icon\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-calendar-alt\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 464c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48V192H0v272zm320-196c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12h-40c-6.6 0-12-5.4-12-12v-40zm0 128c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12h-40c-6.6 0-12-5.4-12-12v-40zM192 268c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12h-40c-6.6 0-12-5.4-12-12v-40zm0 128c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12h-40c-6.6 0-12-5.4-12-12v-40zM64 268c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12H76c-6.6 0-12-5.4-12-12v-40zm0 128c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12H76c-6.6 0-12-5.4-12-12v-40zM400 64h-48V16c0-8.8-7.2-16-16-16h-32c-8.8 0-16 7.2-16 16v48H160V16c0-8.8-7.2-16-16-16h-32c-8.8 0-16 7.2-16 16v48H48C21.5 64 0 85.5 0 112v48h448v-48c0-26.5-21.5-48-48-48z\"><\/path><\/svg><\/span><\/div><\/div><div class=\"timeline-item__meta\"><div class=\"timeline-item__meta-content\">1. Oktober 2023<\/div><\/div><\/div><div class=\"jet-timeline-item  elementor-repeater-item-889f989 jet-timeline-item--image-inside\">\n\t<div class=\"timeline-item__card\">\n\t\t<div class=\"timeline-item__card-inner\">\n\t\t\t\t\t\t\t\t<div class=\"timeline-item__card-content\">\n\t\t\t\t\t<div class=\"timeline-item__meta\"><div class=\"timeline-item__meta-content\">31. Januar 2024<\/div><\/div><div class=\"timeline-item__card-desc\">Abgabe des ersten Quartal-Berichts f\u00fcr den Zeitraum Oktober bis Dezember 2023: Angabe der Warenmenge, gesamter grauer Emissionen (Anhang III), gesamter indirekter Emissionen &amp;\ndes CO2-Preises im Herkunftsland<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"timeline-item__card-arrow\"><\/div>\n\t<\/div>\n\t<div class=\"timeline-item__point\"><div class=\"timeline-item__point-content timeline-item__point-content--icon\"><span class=\"jet-elements-icon\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-calendar-alt\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 464c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48V192H0v272zm320-196c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12h-40c-6.6 0-12-5.4-12-12v-40zm0 128c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12h-40c-6.6 0-12-5.4-12-12v-40zM192 268c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12h-40c-6.6 0-12-5.4-12-12v-40zm0 128c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12h-40c-6.6 0-12-5.4-12-12v-40zM64 268c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12H76c-6.6 0-12-5.4-12-12v-40zm0 128c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12H76c-6.6 0-12-5.4-12-12v-40zM400 64h-48V16c0-8.8-7.2-16-16-16h-32c-8.8 0-16 7.2-16 16v48H160V16c0-8.8-7.2-16-16-16h-32c-8.8 0-16 7.2-16 16v48H48C21.5 64 0 85.5 0 112v48h448v-48c0-26.5-21.5-48-48-48z\"><\/path><\/svg><\/span><\/div><\/div><div class=\"timeline-item__meta\"><div class=\"timeline-item__meta-content\">31. Januar 2024<\/div><\/div><\/div><div class=\"jet-timeline-item  elementor-repeater-item-2fe62ee jet-timeline-item--image-inside\">\n\t<div class=\"timeline-item__card\">\n\t\t<div class=\"timeline-item__card-inner\">\n\t\t\t\t\t\t\t\t<div class=\"timeline-item__card-content\">\n\t\t\t\t\t<div class=\"timeline-item__meta\"><div class=\"timeline-item__meta-content\">01. Januar 2025<\/div><\/div><div class=\"timeline-item__card-desc\">Beantragung des Status \"Zugelassene:r CBAM-Anmelder:in\"<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"timeline-item__card-arrow\"><\/div>\n\t<\/div>\n\t<div class=\"timeline-item__point\"><div class=\"timeline-item__point-content timeline-item__point-content--icon\"><span class=\"jet-elements-icon\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-calendar-alt\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 464c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48V192H0v272zm320-196c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12h-40c-6.6 0-12-5.4-12-12v-40zm0 128c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12h-40c-6.6 0-12-5.4-12-12v-40zM192 268c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12h-40c-6.6 0-12-5.4-12-12v-40zm0 128c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12h-40c-6.6 0-12-5.4-12-12v-40zM64 268c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12H76c-6.6 0-12-5.4-12-12v-40zm0 128c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12H76c-6.6 0-12-5.4-12-12v-40zM400 64h-48V16c0-8.8-7.2-16-16-16h-32c-8.8 0-16 7.2-16 16v48H160V16c0-8.8-7.2-16-16-16h-32c-8.8 0-16 7.2-16 16v48H48C21.5 64 0 85.5 0 112v48h448v-48c0-26.5-21.5-48-48-48z\"><\/path><\/svg><\/span><\/div><\/div><div class=\"timeline-item__meta\"><div class=\"timeline-item__meta-content\">01. Januar 2025<\/div><\/div><\/div><div class=\"jet-timeline-item  elementor-repeater-item-f795559 jet-timeline-item--image-inside\">\n\t<div class=\"timeline-item__card\">\n\t\t<div class=\"timeline-item__card-inner\">\n\t\t\t\t\t\t\t\t<div class=\"timeline-item__card-content\">\n\t\t\t\t\t<div class=\"timeline-item__meta\"><div class=\"timeline-item__meta-content\">01. Januar 2026<\/div><\/div><h5 class=\"timeline-item__card-title\">Beginn der Implementierungsphase und Zertifikatehandel<\/h5><div class=\"timeline-item__card-desc\">Vollst\u00e4ndige Verpflichtungen und - Abgabe eines zus\u00e4tzlichen j\u00e4hrlichen CBAM-Berichts bis 31. Mai: Angabe der gesamten Emissionen sowie Gesamtmenge der importierten Waren,\nKauf der erforderlichen Anzahl von CBAM-Zertifikaten, \nBer\u00fccksichtigung von bereits im Herkunftsland gezahlten CO2-Preisen &amp; Pr\u00fcfberichte akkreditierter Pr\u00fcfender<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"timeline-item__card-arrow\"><\/div>\n\t<\/div>\n\t<div class=\"timeline-item__point\"><div class=\"timeline-item__point-content timeline-item__point-content--icon\"><span class=\"jet-elements-icon\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-calendar-alt\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 464c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48V192H0v272zm320-196c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12h-40c-6.6 0-12-5.4-12-12v-40zm0 128c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12h-40c-6.6 0-12-5.4-12-12v-40zM192 268c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12h-40c-6.6 0-12-5.4-12-12v-40zm0 128c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12h-40c-6.6 0-12-5.4-12-12v-40zM64 268c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12H76c-6.6 0-12-5.4-12-12v-40zm0 128c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12H76c-6.6 0-12-5.4-12-12v-40zM400 64h-48V16c0-8.8-7.2-16-16-16h-32c-8.8 0-16 7.2-16 16v48H160V16c0-8.8-7.2-16-16-16h-32c-8.8 0-16 7.2-16 16v48H48C21.5 64 0 85.5 0 112v48h448v-48c0-26.5-21.5-48-48-48z\"><\/path><\/svg><\/span><\/div><\/div><div class=\"timeline-item__meta\"><div class=\"timeline-item__meta-content\">01. Januar 2026<\/div><\/div><\/div><div class=\"jet-timeline-item  elementor-repeater-item-4c07485 jet-timeline-item--image-inside\">\n\t<div class=\"timeline-item__card\">\n\t\t<div class=\"timeline-item__card-inner\">\n\t\t\t\t\t\t\t\t<div class=\"timeline-item__card-content\">\n\t\t\t\t\t<div class=\"timeline-item__meta\"><div class=\"timeline-item__meta-content\">01. Januar 2034<\/div><\/div><div class=\"timeline-item__card-desc\">CBAM-Zertifikate decken 100 % der inkludierten Emissionen ab,\n                                                                                         keine kostenlose Zuteilung mehr von Zertifikaten<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"timeline-item__card-arrow\"><\/div>\n\t<\/div>\n\t<div class=\"timeline-item__point\"><div class=\"timeline-item__point-content timeline-item__point-content--icon\"><span class=\"jet-elements-icon\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-calendar-alt\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 464c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48V192H0v272zm320-196c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12h-40c-6.6 0-12-5.4-12-12v-40zm0 128c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12h-40c-6.6 0-12-5.4-12-12v-40zM192 268c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12h-40c-6.6 0-12-5.4-12-12v-40zm0 128c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12h-40c-6.6 0-12-5.4-12-12v-40zM64 268c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12H76c-6.6 0-12-5.4-12-12v-40zm0 128c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12H76c-6.6 0-12-5.4-12-12v-40zM400 64h-48V16c0-8.8-7.2-16-16-16h-32c-8.8 0-16 7.2-16 16v48H160V16c0-8.8-7.2-16-16-16h-32c-8.8 0-16 7.2-16 16v48H48C21.5 64 0 85.5 0 112v48h448v-48c0-26.5-21.5-48-48-48z\"><\/path><\/svg><\/span><\/div><\/div><div class=\"timeline-item__meta\"><div class=\"timeline-item__meta-content\">01. Januar 2034<\/div><\/div><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a117401 elementor-widget elementor-widget-text-editor\" data-id=\"3a117401\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Bei unvollst\u00e4ndigen oder fehlerhaften Berichten wird zun\u00e4chst ein Berichtigungsverfahren eingleitet. Erfolgt dies nicht, droht eine Strafzahlung in H\u00f6he von 10 \u2013 50 Euro je Tonne nicht bzw. falsch gemeldeter Emissionen. Ab der Implementierungsphase werden Strafen von 100 Euro je Tonne CO2-Emissionen verh\u00e4ngt, wenn nicht ausreichend Zertifikate vorliegen. Zus\u00e4tzlich dazu m\u00fcssen die fehlenden Zertifikate nachgekauft werden.<\/p><p>Kritisiert am CBAM wird vor allem die \u00fcberschnelle Umsetzung, die Unternehmen kaum Zeit lie\u00df, sich auf die Anforderungen vorzubereiten und der hohe b\u00fcrokratische Aufwand. So kritisiert die <a href=\"https:\/\/www.dihk.de\/de\/aktuelles-und-presse\/aktuelle-informationen\/cbam-start-betriebe-brauchen-schonfristen-und-bagatellgrenzen-103228\">DIHK<\/a>, dass von dem CBAM beispielsweise auch Allerweltswaren wie etwa Schrauben betroffen sind, f\u00fcr die dann ab einem Wert von 150 Euro jedes Quartal fast 300 Datenfelder gef\u00fcllt werden m\u00fcssen.<\/p><p>Trotz allem stellt der CBAM einen wichtigen Mechanismus dar, um Wettbewerbsnachteile zu vermeiden und letzendlich die Klimaziele effektiv zu verfolgen.<\/p><p>Auf der <a href=\"https:\/\/taxation-customs.ec.europa.eu\/carbon-border-adjustment-mechanism_en\">CBAM-Webseite<\/a> der europ\u00e4ischen Kommission sind weitreichende Informationen zu finden.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65138aa elementor-cta--skin-cover elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"65138aa\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.weshyft.com\/wp-content\/uploads\/2022\/01\/WeShyft-Newletter-Banner-3-1024x576.png);\" role=\"img\" aria-label=\"WeShyft Newletter Banner (3)\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tlost in Regulation? \t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tMelde Dich zu unserem Newsletter an und bleibe stets auf dem neuesten Stand zu aktuellen ESG Gesetzgebungen.\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"https:\/\/www.weshyft.com\/en\/newsletter\/\">\n\t\t\t\t\t\tJetzt anmelden\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Der CBAM (Carbon Border Adjustment Mechanism) ist am 01. Oktober 2023 in Kraft getreten und wurde damit zur Pflicht f\u00fcr viele Importeure in der EU. Dieser Artikel gibt einen \u00dcberblick \u00fcber die Hintergr\u00fcnde und Inhalte sowie zu Zeitplan und Anforderungen f\u00fcr betroffene Unternehmen des CBAM. Die erste Frist ist bereits am 31. Januar 2024, zu [&hellip;]<\/p>","protected":false},"author":1,"featured_media":13381,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":[126],"meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"CBAM \u2013 das CO2 Grenzausgleichssystem der EU","_seopress_titles_desc":"Der CBAM (Carbon Border Adjustment Mechanism) ist am 01. Oktober 2023 in Kraft getreten und wurde damit zur Pflicht f\u00fcr viele Importeure in der EU. Dieser Artikel gibt einen \u00dcberblick \u00fcber die Hintergr\u00fcnde und Inhalte sowie zu Zeitplan und Anforderungen f\u00fcr betroffene Unternehmen des CBAM. Die erste Frist ist bereits am 31. Januar 2024, zu der CBAM-Berichte bei der EU-Kommission eingereicht werden m\u00fcssen.","_seopress_robots_index":"","content-type":"","inline_featured_image":false,"editor_plus_copied_stylings":"{}","footnotes":""},"categories":[118,10],"tags":[],"thema":[129,128],"class_list":["post-13355","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-klimaschutz","category-lieferkette","thema-klimaschutz","thema-lieferkette","format-artikel"],"_links":{"self":[{"href":"https:\/\/www.weshyft.com\/en\/wp-json\/wp\/v2\/posts\/13355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weshyft.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weshyft.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weshyft.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weshyft.com\/en\/wp-json\/wp\/v2\/comments?post=13355"}],"version-history":[{"count":5,"href":"https:\/\/www.weshyft.com\/en\/wp-json\/wp\/v2\/posts\/13355\/revisions"}],"predecessor-version":[{"id":13387,"href":"https:\/\/www.weshyft.com\/en\/wp-json\/wp\/v2\/posts\/13355\/revisions\/13387"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weshyft.com\/en\/wp-json\/wp\/v2\/media\/13381"}],"wp:attachment":[{"href":"https:\/\/www.weshyft.com\/en\/wp-json\/wp\/v2\/media?parent=13355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weshyft.com\/en\/wp-json\/wp\/v2\/categories?post=13355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weshyft.com\/en\/wp-json\/wp\/v2\/tags?post=13355"},{"taxonomy":"thema","embeddable":true,"href":"https:\/\/www.weshyft.com\/en\/wp-json\/wp\/v2\/thema?post=13355"},{"taxonomy":"format","embeddable":true,"href":"https:\/\/www.weshyft.com\/en\/wp-json\/wp\/v2\/format?post=13355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}